{"id":9817,"date":"2024-04-23T12:23:02","date_gmt":"2024-04-23T11:23:02","guid":{"rendered":"https:\/\/www.shs-capital.eu\/?p=9817"},"modified":"2026-03-06T13:55:28","modified_gmt":"2026-03-06T12:55:28","slug":"shs-partner-dr-andre-zimmermann-und-shs-investment-manager-hannes-kempter-auf-der-j-p-morgan-konferenz","status":"publish","type":"post","link":"https:\/\/www.shs-capital.eu\/de\/shs-partner-dr-andre-zimmermann-und-shs-investment-manager-hannes-kempter-auf-der-j-p-morgan-konferenz\/","title":{"rendered":"SHS Partner Dr. Andr\u00e9 Zimmermann und SHS Investment Manager Hannes Kempter auf der J.P. Morgan Konferenz"},"content":{"rendered":"\n<p>Im Januar machten sich SHS Partner Andr\u00e9 Zimmermann und SHS Investment Manager Hannes Kempter auf den Weg nach San Francisco zur J.P. Morgan Konferenz. Das Wetter meinte es zum ersten Mal seit langem wieder gut mit der Konferenz und war nicht gewohnt regnerisch, sondern angenehm sonnig. Auch die Atmosph\u00e4re auf der Konferenz war nach der langen Coronazeit nicht getr\u00fcbt, sondern zeugte von Aufbruchsstimmung und frischem Wind.<\/p>\n\n\n\n<p>Die Zeit der Konferenz nutzten die Kollegen f\u00fcr viele Treffen mit Strategen, potenziellen Targets sowie wichtigen Kontakten im Bereich Business Development. Dabei standen das Kennenlernen und Kn\u00fcpfen neuer Kontakte, der aktuelle Investment-Fokus sowie das Vorstellen des SHS-Portfolios auf der Tagesordnung. Ebenfalls aktiv auf der Messe vertreten waren die SHS-Portfoliounternehmen CoreMedic, SIS Medical und die ndd.<\/p>\n\n\n\n<p>Wenn Sie ebenfalls Interesse haben sollten, mit uns in Kontakt zu treten, um sich auszutauschen oder gemeinsame Projekte in Angriff zu nehmen, melden Sie sich gerne.<\/p>\n\n\n\n<ol class=\"wp-block-list\" style=\"list-style-type:upper-roman\"><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Im Januar machten sich SHS Partner Andr\u00e9 Zimmermann und SHS Investment Manager Hannes Kempter auf den Weg nach San Francisco zur J.P. Morgan Konferenz. Das Wetter meinte es zum ersten Mal seit langem wieder gut mit der Konferenz und war nicht gewohnt regnerisch, sondern angenehm sonnig. Auch die Atmosph\u00e4re auf der Konferenz war nach der [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[91],"tags":[],"class_list":["post-9817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shs-news-de"],"acf":[],"author_name":"SHS Capital","_links":{"self":[{"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/posts\/9817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/comments?post=9817"}],"version-history":[{"count":0,"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/posts\/9817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/media\/9818"}],"wp:attachment":[{"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/media?parent=9817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/categories?post=9817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shs-capital.eu\/de\/wp-json\/wp\/v2\/tags?post=9817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}